{"id":1325,"date":"2022-10-02T18:40:50","date_gmt":"2022-10-02T18:40:50","guid":{"rendered":"https:\/\/hclinical.com\/ensayos-descentralizados-en-america-latina-ensayos-clinicos-aplicados\/"},"modified":"2023-10-31T22:57:34","modified_gmt":"2023-10-31T22:57:34","slug":"ensayos-descentralizados-en-america-latina-ensayos-clinicos-aplicados","status":"publish","type":"post","link":"https:\/\/hclinical.com\/es\/ensayos-descentralizados-en-america-latina-ensayos-clinicos-aplicados\/","title":{"rendered":"Ensayos descentralizados en Am\u00e9rica Latina: Ensayos Cl\u00ednicos Aplicados"},"content":{"rendered":"\n<p class=\"wp-block-paragraph\">Applied Clinical Trials Magazine public\u00f3 un art\u00edculo perspicaz del presidente de H Clinical, Mitchell Parrish, titulado <a href=\"https:\/\/www.appliedclinicaltrialsonline.com\/view\/game-changer-transformative-decentralized-clinical-trials-emerge-in-latin-america\" target=\"_blank\" rel=\"noreferrer noopener\">Game Changer: Transformative Decentralized Clinical Trials Emerge in Latin<\/a> America. Los beneficios de investigar en la regi\u00f3n son muchos. Este art\u00edculo descubre c\u00f3mo los ensayos cl\u00ednicos descentralizados (ECD) aumentan las probabilidades de \u00e9xito de los ensayos cl\u00ednicos globales. Ampliar la captaci\u00f3n de pacientes atendiendo a la diversidad es la principal ventaja. Pero lo que es m\u00e1s importante, ayudar a los pacientes facilit\u00e1ndoles el acceso a tratamientos m\u00e9dicos en zonas rurales es un factor enorme. H Clinical ayuda a los pacientes a superar el reto de la distancia en una regi\u00f3n con algunos de los transportes menos fiables. La inversi\u00f3n en la regi\u00f3n tambi\u00e9n ayuda a las comunidades al crear puestos de trabajo locales fuera de las ciudades, donde los centros de investigaci\u00f3n son menos accesibles.<\/p>\n\n<h3 class=\"wp-block-heading\">Mejorar las experiencias centradas en el paciente<\/h3>\n\n<p class=\"wp-block-paragraph\">El tema de moda en la investigaci\u00f3n (y la atenci\u00f3n sanitaria) durante la \u00faltima d\u00e9cada es la centralidad del paciente. Y aunque se habla mucho de ello, apenas hubo avances hasta que la pandemia de COVID-19 oblig\u00f3 a cambiar las modalidades de ensayo. Los DCT nacieron de la necesidad. Y ahora existe una oportunidad real de fomentar un cambio s\u00edsmico: hacer de los pacientes el epicentro de la investigaci\u00f3n (en lugar de los centros). Esto est\u00e1 ocurriendo en Am\u00e9rica Latina. El art\u00edculo habla extensamente de c\u00f3mo conocer a los pacientes all\u00ed donde est\u00e1n alivia muchos inconvenientes de la inscripci\u00f3n.  <\/p>\n\n<h3 class=\"wp-block-heading\">Superar los objetivos de los ensayos descentralizados en Am\u00e9rica Latina<\/h3>\n\n<p class=\"wp-block-paragraph\">Si facilita la inscripci\u00f3n en los ensayos y reduce las cargas para los pacientes, repercutir\u00e1 positivamente en el reclutamiento y la retenci\u00f3n. Una mayor participaci\u00f3n, al tiempo que se ayuda a los pacientes a superar el reto de la distancia, contribuye a mejorar la diversidad en las poblaciones de pacientes. Todos ganan. Y en Am\u00e9rica Latina, esto significa atender a los pacientes de la mejor manera posible. Para lograrlo, los patrocinadores del estudio necesitan un socio que domine todos los elementos necesarios para <a href=\"https:\/\/hclinical.com\/es\/?page_id=332\" target=\"_blank\" rel=\"noreferrer noopener\">llevar a cabo la investigaci\u00f3n en toda la regi\u00f3n<\/a>.<\/p>\n\n<h3 class=\"wp-block-heading\">Escalar con \u00e9xito la ejecuci\u00f3n de los juicios<\/h3>\n\n<p class=\"wp-block-paragraph\">La mina terrestre m\u00e1s com\u00fan que los patrocinadores deben evitar cuando se trata de ejecutar con \u00e9xito un SES: la falta de infraestructura localizada. El art\u00edculo revela c\u00f3mo este denominador com\u00fan puede hacer o deshacer las inversiones en investigaci\u00f3n en Am\u00e9rica Latina. En primer lugar, se necesita una <a href=\"https:\/\/hclinical.com\/es\/?page_id=336\" target=\"_blank\" rel=\"noreferrer noopener\">buena<\/a> estrategia <a href=\"https:\/\/hclinical.com\/es\/?page_id=336\" target=\"_blank\" rel=\"noreferrer noopener\">log\u00edstica<\/a> y de personal para el acceso rural y la cobertura multinacional transfronteriza. Adem\u00e1s, una mano de obra local diversa genera confianza entre la poblaci\u00f3n local y mejora la coordinaci\u00f3n asistencial. Esto aumenta el compromiso y la retenci\u00f3n de los pacientes, mejorando a\u00fan m\u00e1s la inscripci\u00f3n en los ensayos.<\/p>\n\n<p class=\"wp-block-paragraph\">Le animamos a <a href=\"https:\/\/www.appliedclinicaltrialsonline.com\/view\/game-changer-transformative-decentralized-clinical-trials-emerge-in-latin-america\" target=\"_blank\" rel=\"noreferrer noopener\">leer el art\u00edculo completo<\/a> para conocer la opini\u00f3n de expertos en la materia de toda la regi\u00f3n. Adem\u00e1s, datos reveladores y experiencias de primera mano de ensayos descentralizados exitosos en Am\u00e9rica Latina le permitir\u00e1n comprender mejor las mejores pr\u00e1cticas eficaces para la ejecuci\u00f3n de ensayos.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Applied Clinical Trials Magazine public\u00f3 un art\u00edculo perspicaz del presidente de H Clinical, Mitchell Parrish, titulado Game Changer: Transformative Decentralized Clinical Trials Emerge in Latin America. Los beneficios de investigar en la regi\u00f3n son muchos. Este art\u00edculo descubre c\u00f3mo los ensayos cl\u00ednicos descentralizados (ECD) aumentan las probabilidades de \u00e9xito de los ensayos cl\u00ednicos globales. Ampliar [&hellip;]<\/p>\n","protected":false},"author":3,"featured_media":779,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[5],"tags":[47,59,45,60],"class_list":["post-1325","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-sin-categorizar","tag-america-latina-es","tag-ensayos-clinicos-aplicados","tag-ensayos-clinicos-descentralizados","tag-estrategia-logistica-es"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.5 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Ensayos descentralizados en Am\u00e9rica Latina: Ensayos Cl\u00ednicos Aplicados - H Clinical<\/title>\n<meta name=\"description\" content=\"Applied Clinical Trials public\u00f3 un perspicaz art\u00edculo de H Clinical que destaca el impacto de los ensayos descentralizados en Am\u00e9rica Latina.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/hclinical.com\/es\/ensayos-descentralizados-en-america-latina-ensayos-clinicos-aplicados\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Ensayos descentralizados en Am\u00e9rica Latina: Ensayos Cl\u00ednicos Aplicados - H Clinical\" \/>\n<meta property=\"og:description\" content=\"Applied Clinical Trials public\u00f3 un perspicaz art\u00edculo de H Clinical que destaca el impacto de los ensayos descentralizados en Am\u00e9rica Latina.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/hclinical.com\/es\/ensayos-descentralizados-en-america-latina-ensayos-clinicos-aplicados\/\" \/>\n<meta property=\"og:site_name\" content=\"H Clinical\" \/>\n<meta property=\"article:published_time\" content=\"2022-10-02T18:40:50+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2023-10-31T22:57:34+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/hclinical.com\/wp-content\/uploads\/2020\/12\/capabilities-clinical-trial.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"300\" \/>\n\t<meta property=\"og:image:height\" content=\"210\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Mitchell Parrish\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Mitchell Parrish\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"3 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/hclinical.com\\\/es\\\/ensayos-descentralizados-en-america-latina-ensayos-clinicos-aplicados\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/hclinical.com\\\/es\\\/ensayos-descentralizados-en-america-latina-ensayos-clinicos-aplicados\\\/\"},\"author\":{\"name\":\"Mitchell Parrish\",\"@id\":\"https:\\\/\\\/hclinical.com\\\/#\\\/schema\\\/person\\\/a036fa1238d1d66ccf0daf7658744514\"},\"headline\":\"Ensayos descentralizados en Am\u00e9rica Latina: Ensayos Cl\u00ednicos Aplicados\",\"datePublished\":\"2022-10-02T18:40:50+00:00\",\"dateModified\":\"2023-10-31T22:57:34+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/hclinical.com\\\/es\\\/ensayos-descentralizados-en-america-latina-ensayos-clinicos-aplicados\\\/\"},\"wordCount\":570,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/hclinical.com\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/hclinical.com\\\/es\\\/ensayos-descentralizados-en-america-latina-ensayos-clinicos-aplicados\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/hclinical.com\\\/wp-content\\\/uploads\\\/2020\\\/12\\\/capabilities-clinical-trial.jpg\",\"keywords\":[\"Am\u00e9rica Latina\",\"Ensayos cl\u00ednicos aplicados\",\"ensayos cl\u00ednicos descentralizados\",\"estrategia log\u00edstica\"],\"articleSection\":[\"Sin categorizar\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/hclinical.com\\\/es\\\/ensayos-descentralizados-en-america-latina-ensayos-clinicos-aplicados\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/hclinical.com\\\/es\\\/ensayos-descentralizados-en-america-latina-ensayos-clinicos-aplicados\\\/\",\"url\":\"https:\\\/\\\/hclinical.com\\\/es\\\/ensayos-descentralizados-en-america-latina-ensayos-clinicos-aplicados\\\/\",\"name\":\"Ensayos descentralizados en Am\u00e9rica Latina: Ensayos Cl\u00ednicos Aplicados - H Clinical\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/hclinical.com\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/hclinical.com\\\/es\\\/ensayos-descentralizados-en-america-latina-ensayos-clinicos-aplicados\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/hclinical.com\\\/es\\\/ensayos-descentralizados-en-america-latina-ensayos-clinicos-aplicados\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/hclinical.com\\\/wp-content\\\/uploads\\\/2020\\\/12\\\/capabilities-clinical-trial.jpg\",\"datePublished\":\"2022-10-02T18:40:50+00:00\",\"dateModified\":\"2023-10-31T22:57:34+00:00\",\"description\":\"Applied Clinical Trials public\u00f3 un perspicaz art\u00edculo de H Clinical que destaca el impacto de los ensayos descentralizados en Am\u00e9rica Latina.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/hclinical.com\\\/es\\\/ensayos-descentralizados-en-america-latina-ensayos-clinicos-aplicados\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/hclinical.com\\\/es\\\/ensayos-descentralizados-en-america-latina-ensayos-clinicos-aplicados\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/hclinical.com\\\/es\\\/ensayos-descentralizados-en-america-latina-ensayos-clinicos-aplicados\\\/#primaryimage\",\"url\":\"https:\\\/\\\/hclinical.com\\\/wp-content\\\/uploads\\\/2020\\\/12\\\/capabilities-clinical-trial.jpg\",\"contentUrl\":\"https:\\\/\\\/hclinical.com\\\/wp-content\\\/uploads\\\/2020\\\/12\\\/capabilities-clinical-trial.jpg\",\"width\":300,\"height\":210},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/hclinical.com\\\/es\\\/ensayos-descentralizados-en-america-latina-ensayos-clinicos-aplicados\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/hclinical.com\\\/es\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Ensayos descentralizados en Am\u00e9rica Latina: Ensayos Cl\u00ednicos Aplicados\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/hclinical.com\\\/#website\",\"url\":\"https:\\\/\\\/hclinical.com\\\/\",\"name\":\"H Clinical\",\"description\":\"Bringing clinical research home\",\"publisher\":{\"@id\":\"https:\\\/\\\/hclinical.com\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/hclinical.com\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/hclinical.com\\\/#organization\",\"name\":\"H Clinical\",\"url\":\"https:\\\/\\\/hclinical.com\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/hclinical.com\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/hclinical.com\\\/wp-content\\\/uploads\\\/2020\\\/12\\\/logo-blue.png\",\"contentUrl\":\"https:\\\/\\\/hclinical.com\\\/wp-content\\\/uploads\\\/2020\\\/12\\\/logo-blue.png\",\"width\":1000,\"height\":328,\"caption\":\"H Clinical\"},\"image\":{\"@id\":\"https:\\\/\\\/hclinical.com\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.linkedin.com\\\/company\\\/h-clinical\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/hclinical.com\\\/#\\\/schema\\\/person\\\/a036fa1238d1d66ccf0daf7658744514\",\"name\":\"Mitchell Parrish\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/692e09e622eb9c73b20411b0e53d0664d27537df062a34f2c0032e3e73038721?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/692e09e622eb9c73b20411b0e53d0664d27537df062a34f2c0032e3e73038721?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/692e09e622eb9c73b20411b0e53d0664d27537df062a34f2c0032e3e73038721?s=96&d=mm&r=g\",\"caption\":\"Mitchell Parrish\"},\"sameAs\":[\"http:\\\/\\\/hclinical.com\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Ensayos descentralizados en Am\u00e9rica Latina: Ensayos Cl\u00ednicos Aplicados - H Clinical","description":"Applied Clinical Trials public\u00f3 un perspicaz art\u00edculo de H Clinical que destaca el impacto de los ensayos descentralizados en Am\u00e9rica Latina.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/hclinical.com\/es\/ensayos-descentralizados-en-america-latina-ensayos-clinicos-aplicados\/","og_locale":"es_ES","og_type":"article","og_title":"Ensayos descentralizados en Am\u00e9rica Latina: Ensayos Cl\u00ednicos Aplicados - H Clinical","og_description":"Applied Clinical Trials public\u00f3 un perspicaz art\u00edculo de H Clinical que destaca el impacto de los ensayos descentralizados en Am\u00e9rica Latina.","og_url":"https:\/\/hclinical.com\/es\/ensayos-descentralizados-en-america-latina-ensayos-clinicos-aplicados\/","og_site_name":"H Clinical","article_published_time":"2022-10-02T18:40:50+00:00","article_modified_time":"2023-10-31T22:57:34+00:00","og_image":[{"width":300,"height":210,"url":"https:\/\/hclinical.com\/wp-content\/uploads\/2020\/12\/capabilities-clinical-trial.jpg","type":"image\/jpeg"}],"author":"Mitchell Parrish","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"Mitchell Parrish","Tiempo de lectura":"3 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/hclinical.com\/es\/ensayos-descentralizados-en-america-latina-ensayos-clinicos-aplicados\/#article","isPartOf":{"@id":"https:\/\/hclinical.com\/es\/ensayos-descentralizados-en-america-latina-ensayos-clinicos-aplicados\/"},"author":{"name":"Mitchell Parrish","@id":"https:\/\/hclinical.com\/#\/schema\/person\/a036fa1238d1d66ccf0daf7658744514"},"headline":"Ensayos descentralizados en Am\u00e9rica Latina: Ensayos Cl\u00ednicos Aplicados","datePublished":"2022-10-02T18:40:50+00:00","dateModified":"2023-10-31T22:57:34+00:00","mainEntityOfPage":{"@id":"https:\/\/hclinical.com\/es\/ensayos-descentralizados-en-america-latina-ensayos-clinicos-aplicados\/"},"wordCount":570,"commentCount":0,"publisher":{"@id":"https:\/\/hclinical.com\/#organization"},"image":{"@id":"https:\/\/hclinical.com\/es\/ensayos-descentralizados-en-america-latina-ensayos-clinicos-aplicados\/#primaryimage"},"thumbnailUrl":"https:\/\/hclinical.com\/wp-content\/uploads\/2020\/12\/capabilities-clinical-trial.jpg","keywords":["Am\u00e9rica Latina","Ensayos cl\u00ednicos aplicados","ensayos cl\u00ednicos descentralizados","estrategia log\u00edstica"],"articleSection":["Sin categorizar"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/hclinical.com\/es\/ensayos-descentralizados-en-america-latina-ensayos-clinicos-aplicados\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/hclinical.com\/es\/ensayos-descentralizados-en-america-latina-ensayos-clinicos-aplicados\/","url":"https:\/\/hclinical.com\/es\/ensayos-descentralizados-en-america-latina-ensayos-clinicos-aplicados\/","name":"Ensayos descentralizados en Am\u00e9rica Latina: Ensayos Cl\u00ednicos Aplicados - H Clinical","isPartOf":{"@id":"https:\/\/hclinical.com\/#website"},"primaryImageOfPage":{"@id":"https:\/\/hclinical.com\/es\/ensayos-descentralizados-en-america-latina-ensayos-clinicos-aplicados\/#primaryimage"},"image":{"@id":"https:\/\/hclinical.com\/es\/ensayos-descentralizados-en-america-latina-ensayos-clinicos-aplicados\/#primaryimage"},"thumbnailUrl":"https:\/\/hclinical.com\/wp-content\/uploads\/2020\/12\/capabilities-clinical-trial.jpg","datePublished":"2022-10-02T18:40:50+00:00","dateModified":"2023-10-31T22:57:34+00:00","description":"Applied Clinical Trials public\u00f3 un perspicaz art\u00edculo de H Clinical que destaca el impacto de los ensayos descentralizados en Am\u00e9rica Latina.","breadcrumb":{"@id":"https:\/\/hclinical.com\/es\/ensayos-descentralizados-en-america-latina-ensayos-clinicos-aplicados\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/hclinical.com\/es\/ensayos-descentralizados-en-america-latina-ensayos-clinicos-aplicados\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/hclinical.com\/es\/ensayos-descentralizados-en-america-latina-ensayos-clinicos-aplicados\/#primaryimage","url":"https:\/\/hclinical.com\/wp-content\/uploads\/2020\/12\/capabilities-clinical-trial.jpg","contentUrl":"https:\/\/hclinical.com\/wp-content\/uploads\/2020\/12\/capabilities-clinical-trial.jpg","width":300,"height":210},{"@type":"BreadcrumbList","@id":"https:\/\/hclinical.com\/es\/ensayos-descentralizados-en-america-latina-ensayos-clinicos-aplicados\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/hclinical.com\/es\/"},{"@type":"ListItem","position":2,"name":"Ensayos descentralizados en Am\u00e9rica Latina: Ensayos Cl\u00ednicos Aplicados"}]},{"@type":"WebSite","@id":"https:\/\/hclinical.com\/#website","url":"https:\/\/hclinical.com\/","name":"H Clinical","description":"Bringing clinical research home","publisher":{"@id":"https:\/\/hclinical.com\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/hclinical.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/hclinical.com\/#organization","name":"H Clinical","url":"https:\/\/hclinical.com\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/hclinical.com\/#\/schema\/logo\/image\/","url":"https:\/\/hclinical.com\/wp-content\/uploads\/2020\/12\/logo-blue.png","contentUrl":"https:\/\/hclinical.com\/wp-content\/uploads\/2020\/12\/logo-blue.png","width":1000,"height":328,"caption":"H Clinical"},"image":{"@id":"https:\/\/hclinical.com\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.linkedin.com\/company\/h-clinical"]},{"@type":"Person","@id":"https:\/\/hclinical.com\/#\/schema\/person\/a036fa1238d1d66ccf0daf7658744514","name":"Mitchell Parrish","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/secure.gravatar.com\/avatar\/692e09e622eb9c73b20411b0e53d0664d27537df062a34f2c0032e3e73038721?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/692e09e622eb9c73b20411b0e53d0664d27537df062a34f2c0032e3e73038721?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/692e09e622eb9c73b20411b0e53d0664d27537df062a34f2c0032e3e73038721?s=96&d=mm&r=g","caption":"Mitchell Parrish"},"sameAs":["http:\/\/hclinical.com"]}]}},"_links":{"self":[{"href":"https:\/\/hclinical.com\/es\/wp-json\/wp\/v2\/posts\/1325","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/hclinical.com\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/hclinical.com\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/hclinical.com\/es\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/hclinical.com\/es\/wp-json\/wp\/v2\/comments?post=1325"}],"version-history":[{"count":0,"href":"https:\/\/hclinical.com\/es\/wp-json\/wp\/v2\/posts\/1325\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/hclinical.com\/es\/wp-json\/wp\/v2\/media\/779"}],"wp:attachment":[{"href":"https:\/\/hclinical.com\/es\/wp-json\/wp\/v2\/media?parent=1325"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/hclinical.com\/es\/wp-json\/wp\/v2\/categories?post=1325"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/hclinical.com\/es\/wp-json\/wp\/v2\/tags?post=1325"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}